{"id":1416,"date":"2025-11-30T21:33:11","date_gmt":"2025-11-30T20:33:11","guid":{"rendered":"https:\/\/tm-alcala-villalbilla.com\/?p=1416"},"modified":"2025-11-30T21:34:18","modified_gmt":"2025-11-30T20:34:18","slug":"fallecio-un-buen-amigo-del-club","status":"publish","type":"post","link":"https:\/\/tm-alcala-villalbilla.com\/index.php\/2025\/11\/30\/fallecio-un-buen-amigo-del-club\/","title":{"rendered":"Falleci\u00f3 un buen amigo del Club."},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbText\u00bb _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Ayer en Madrid, falleci\u00f3 un buen Amigo del Club, <strong>I\u00f1igo Villacieros<\/strong>.<\/p>\n<p>Con todo nuestro respeto y cari\u00f1o hacia el y su familia. <strong>D<\/strong>escanse <strong>E<\/strong>n <strong>P<\/strong>az.<\/p>\n<ul class=\"et_post_gallery clearfix\">\n\t\t\t\t\t<li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo1.jpg\" title=\"Homenaje I\u00f1igo1\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo1-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo2.jpg\" title=\"Homenaje I\u00f1igo2\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo2-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo3.jpg\" title=\"Homenaje I\u00f1igo3\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo3-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo4.jpg\" title=\"Homenaje I\u00f1igo4\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo4-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo5.jpg\" title=\"Homenaje I\u00f1igo5\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo5-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo6.jpg\" title=\"Homenaje I\u00f1igo6\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo6-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo7.jpg\" title=\"Homenaje I\u00f1igo7\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo7-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo8.jpg\" title=\"Homenaje I\u00f1igo8\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo8-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo9.jpg\" title=\"Homenaje I\u00f1igo9\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo9-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer en Madrid, falleci\u00f3 un buen Amigo del Club, I\u00f1igo Villacieros. Con todo nuestro respeto y cari\u00f1o hacia el y su familia. Descanse En Paz. <ul class=\"et_post_gallery clearfix\">\n\t\t\t\t\t<li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo1.jpg\" title=\"Homenaje I\u00f1igo1\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo1-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo2.jpg\" title=\"Homenaje I\u00f1igo2\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo2-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo3.jpg\" title=\"Homenaje I\u00f1igo3\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo3-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo4.jpg\" title=\"Homenaje I\u00f1igo4\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo4-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo5.jpg\" title=\"Homenaje I\u00f1igo5\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo5-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo6.jpg\" title=\"Homenaje I\u00f1igo6\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo6-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo7.jpg\" title=\"Homenaje I\u00f1igo7\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo7-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo8.jpg\" title=\"Homenaje I\u00f1igo8\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo8-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo9.jpg\" title=\"Homenaje I\u00f1igo9\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img width=\"400\" height=\"284\" src=\"https:\/\/tm-alcala-villalbilla.com\/wp-content\/uploads\/2025\/11\/Homenaje-Inigo9-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul><\/p>\n","protected":false},"author":1,"featured_media":1426,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>Ayer en Madrid, falleci\u00f3 un buen Amigo del Club, <strong>I\u00f1igo Villacieros<\/strong>.<\/p><p>Con todo nuestro respeto y cari\u00f1o hacia el y su familia <strong>D<\/strong>escanse <strong>E<\/strong>n <strong>P<\/strong>az.<\/p><p>[gallery ids=\"1417,1418,1419,1420,1421,1422,1423,1424,1425\"]<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/posts\/1416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/comments?post=1416"}],"version-history":[{"count":4,"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/posts\/1416\/revisions"}],"predecessor-version":[{"id":1430,"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/posts\/1416\/revisions\/1430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/media\/1426"}],"wp:attachment":[{"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/media?parent=1416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/categories?post=1416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tm-alcala-villalbilla.com\/index.php\/wp-json\/wp\/v2\/tags?post=1416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}